{"id":4166,"date":"2020-12-21T09:53:17","date_gmt":"2020-12-21T09:53:17","guid":{"rendered":"https:\/\/www.csw-parts-gmbh.com\/einwellenextruder\/"},"modified":"2021-10-27T12:07:35","modified_gmt":"2021-10-27T12:07:35","slug":"extrudeuses-monovis","status":"publish","type":"page","link":"https:\/\/www.csw-parts-gmbh.com\/fr\/extrudeuses-monovis\/","title":{"rendered":"Extrudeuses Monovis"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4166\" class=\"elementor elementor-4166 elementor-656\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b72ddb5 elementor-section-stretched elementor-section-content-middle elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"b72ddb5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-644cd46b\" data-id=\"644cd46b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation_mobile&quot;:&quot;fadeIn&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c75961 elementor-widget elementor-widget-image\" data-id=\"6c75961\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"606\" height=\"341\" src=\"https:\/\/www.csw-parts-gmbh.com\/wp-content\/uploads\/2021\/02\/Einwellenextruder.jpg\" class=\"attachment-large size-large wp-image-4171\" alt=\"\" srcset=\"https:\/\/www.csw-parts-gmbh.com\/wp-content\/uploads\/2021\/02\/Einwellenextruder.jpg 606w, https:\/\/www.csw-parts-gmbh.com\/wp-content\/uploads\/2021\/02\/Einwellenextruder-300x169.jpg 300w, https:\/\/www.csw-parts-gmbh.com\/wp-content\/uploads\/2021\/02\/Einwellenextruder-260x146.jpg 260w, https:\/\/www.csw-parts-gmbh.com\/wp-content\/uploads\/2021\/02\/Einwellenextruder-50x28.jpg 50w, https:\/\/www.csw-parts-gmbh.com\/wp-content\/uploads\/2021\/02\/Einwellenextruder-133x75.jpg 133w\" sizes=\"(max-width:767px) 480px, 606px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-912a883\" data-id=\"912a883\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fb44e67 elementor-section-content-middle elementor-section-full_width elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"fb44e67\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-fd0fdd2\" data-id=\"fd0fdd2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-047ed40 elementor-widget elementor-widget-text-editor\" data-id=\"047ed40\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>Extrudeuses Monovis<\/h1><p><strong>Pi\u00e8ces d\u00b4usure pour Extrudeuses Monovis<\/strong><\/p><p>Les extrudeuses monovis se rencontrent souvent dans l\u00b4industrie des aliments pour animaux. Nous pouvons vous offrir de multiples solutions pour des pi\u00e8ces d\u00b4usure telles que Vis &amp; Fourreaux, Plaques fili\u00e8res et Couteaux et tout autre type de pi\u00e8ce accessoires de petite ou grosse dimension.<\/p><blockquote><p>\u00ab Nous avons une solution pour presque toutes les machines extrudeuses rencontr\u00e9es dans l\u00b4industrie \u00bb<\/p><\/blockquote><p>Andritz, Extru-Tech, Wenger et bien d\u00b4autres constructeurs : des machines que nous connaissons bien. Consultez-nous pour vos pi\u00e8ces d\u00b4usure et de rechange.<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-632e554 elementor-align-center elementor-widget__width-auto elementor-hidden-phone elementor-widget elementor-widget-button\" data-id=\"632e554\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-file-pdf\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Liste Constructeurs Machines<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cd32908 elementor-align-center elementor-widget__width-auto elementor-hidden-phone elementor-widget elementor-widget-button\" data-id=\"cd32908\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-file-pdf\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Liste des Mati\u00e8res<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-18fe054 elementor-align-center elementor-widget__width-auto elementor-hidden-phone elementor-widget elementor-widget-button\" data-id=\"18fe054\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/www.csw-parts-gmbh.com\/fr\/fabrication-dextrudeuse\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En savoir plus sur la Fabrication<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c09b958 elementor-widget elementor-widget-spacer\" data-id=\"c09b958\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c8ec45e elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c8ec45e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-f2d2ac7\" data-id=\"f2d2ac7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f760cc4 elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"f760cc4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-file-pdf\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Liste Constructeurs Machines<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a922b36 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"a922b36\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-119ee37\" data-id=\"119ee37\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-59e2242 elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"59e2242\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-file-pdf\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Liste des Mati\u00e8res<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f73f7f7 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f73f7f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5b4c26c\" data-id=\"5b4c26c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4baa9c9 elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"4baa9c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/www.csw-parts-gmbh.com\/fr\/fabrication-dextrudeuse\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En savoir plus sur la Fabrication<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1cdac4a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1cdac4a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3753ed34 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3753ed34\" data-element_type=\"section\" data-e-type=\"section\" id=\"products\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1a8fed1a\" data-id=\"1a8fed1a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c949662 elementor-widget elementor-widget-text-editor\" data-id=\"c949662\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 style=\"text-align: center;\"><em>Avantages<\/em><\/h3><h6 style=\"text-align: center;\">M\u00e9trologie \/ Ing\u00e9nierie \/ Optimisation \/ Fabrication<\/h6>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-eed411e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eed411e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-e7b9610\" data-id=\"e7b9610\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-794416cd elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"794416cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-caret-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Pi\u00e8ces d\u00b4usure et de rechange en acier inoxydable<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-caret-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">S\u00e9lection de mat\u00e9riaux plus performants<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-caret-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Solutions alternatives pour vos pi\u00e8ces d\u00b4usure et de rechange<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-caret-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Ing\u00e9nierie suivant besoin client incluant techniques de scannage en 3D<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-caret-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Modifications, Ajustements, R\u00e9parations et Remise \u00e0 neuf du mat\u00e9riel pour extrusion <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12d08939 elementor-hidden-phone elementor-widget elementor-widget-spacer\" data-id=\"12d08939\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-18607c4f elementor-section-height-min-height elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-items-middle\" data-id=\"18607c4f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5905202d\" data-id=\"5905202d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a8fa6e4 elementor-widget elementor-widget-heading\" data-id=\"4a8fa6e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Demande de devis\n<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63b68812 elementor-widget elementor-widget-heading\" data-id=\"63b68812\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vous avez r\u00e9guli\u00e8rement besoin de pi\u00e8ces d\u00b4usure et de rechange\u00a0? \n<br>\nNous vous les livrons\u00a0!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3182d933 elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"3182d933\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"https:\/\/www.csw-parts-gmbh.com\/fr\/interlocuteurs\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contact<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Extrudeuses Monovis Pi\u00e8ces d\u00b4usure pour Extrudeuses Monovis Les extrudeuses monovis se rencontrent souvent dans l\u00b4industrie des aliments pour animaux. Nous pouvons vous offrir de multiples solutions<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":2,"featured_media":4099,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-4166","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Extrudeuses Monovis : CSW-PARTS GmbH, Fabrication, Entretien<\/title>\n<meta name=\"description\" content=\"Extrudeuses Monovis - R\u00e9paration, fabrication, maintenance, montage et d\u00e9montage et analyse. \u2605 CSW-PARTS GmbH - Extrudeuse - Technologie \u2605\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.csw-parts-gmbh.com\/fr\/extrudeuses-monovis\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Extrudeuses Monovis : CSW-PARTS GmbH, Fabrication, Entretien\" \/>\n<meta property=\"og:description\" content=\"Extrudeuses Monovis - R\u00e9paration, fabrication, maintenance, montage et d\u00e9montage et analyse. \u2605 CSW-PARTS GmbH - Extrudeuse - Technologie \u2605\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.csw-parts-gmbh.com\/fr\/extrudeuses-monovis\/\" \/>\n<meta property=\"og:site_name\" content=\"CSW-PARTS GmbH\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-27T12:07:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.csw-parts-gmbh.com\/wp-content\/uploads\/2021\/02\/collage-einwelle.png\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.csw-parts-gmbh.com\\\/fr\\\/extrudeuses-monovis\\\/\",\"url\":\"https:\\\/\\\/www.csw-parts-gmbh.com\\\/fr\\\/extrudeuses-monovis\\\/\",\"name\":\"Extrudeuses Monovis : CSW-PARTS GmbH, Fabrication, Entretien\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.csw-parts-gmbh.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.csw-parts-gmbh.com\\\/fr\\\/extrudeuses-monovis\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.csw-parts-gmbh.com\\\/fr\\\/extrudeuses-monovis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.csw-parts-gmbh.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/collage-einwelle.png\",\"datePublished\":\"2020-12-21T09:53:17+00:00\",\"dateModified\":\"2021-10-27T12:07:35+00:00\",\"description\":\"Extrudeuses Monovis - R\u00e9paration, fabrication, maintenance, montage et d\u00e9montage et analyse. \u2605 CSW-PARTS GmbH - Extrudeuse - Technologie \u2605\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.csw-parts-gmbh.com\\\/fr\\\/extrudeuses-monovis\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.csw-parts-gmbh.com\\\/fr\\\/extrudeuses-monovis\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.csw-parts-gmbh.com\\\/fr\\\/extrudeuses-monovis\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.csw-parts-gmbh.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/collage-einwelle.png\",\"contentUrl\":\"https:\\\/\\\/www.csw-parts-gmbh.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/collage-einwelle.png\",\"width\":960,\"height\":720,\"caption\":\"Einwellenextruder - Extruder Experte\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.csw-parts-gmbh.com\\\/fr\\\/extrudeuses-monovis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.csw-parts-gmbh.com\\\/fr\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Extrudeuses Monovis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.csw-parts-gmbh.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.csw-parts-gmbh.com\\\/fr\\\/\",\"name\":\"CSW-PARTS GmbH\",\"description\":\"Spezialist f\u00fcr Extruder\u2013Technologie. Hauptverschlei\u00dfteile, wie Schnecken, Geh\u00e4usen, B\u00fcchsen, Wellen und Lochplatten, bis hin zu diversen anderen Verschlei\u00dfteilen.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.csw-parts-gmbh.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.csw-parts-gmbh.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.csw-parts-gmbh.com\\\/fr\\\/#organization\",\"name\":\"CSW-PARTS GmbH\",\"url\":\"https:\\\/\\\/www.csw-parts-gmbh.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.csw-parts-gmbh.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.csw-parts-gmbh.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Logo-transparent-01-3.png\",\"contentUrl\":\"https:\\\/\\\/www.csw-parts-gmbh.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Logo-transparent-01-3.png\",\"width\":803,\"height\":368,\"caption\":\"CSW-PARTS GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.csw-parts-gmbh.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Extrudeuses Monovis : CSW-PARTS GmbH, Fabrication, Entretien","description":"Extrudeuses Monovis - R\u00e9paration, fabrication, maintenance, montage et d\u00e9montage et analyse. \u2605 CSW-PARTS GmbH - Extrudeuse - Technologie \u2605","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.csw-parts-gmbh.com\/fr\/extrudeuses-monovis\/","og_locale":"fr_FR","og_type":"article","og_title":"Extrudeuses Monovis : CSW-PARTS GmbH, Fabrication, Entretien","og_description":"Extrudeuses Monovis - R\u00e9paration, fabrication, maintenance, montage et d\u00e9montage et analyse. \u2605 CSW-PARTS GmbH - Extrudeuse - Technologie \u2605","og_url":"https:\/\/www.csw-parts-gmbh.com\/fr\/extrudeuses-monovis\/","og_site_name":"CSW-PARTS GmbH","article_modified_time":"2021-10-27T12:07:35+00:00","og_image":[{"width":960,"height":720,"url":"https:\/\/www.csw-parts-gmbh.com\/wp-content\/uploads\/2021\/02\/collage-einwelle.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.csw-parts-gmbh.com\/fr\/extrudeuses-monovis\/","url":"https:\/\/www.csw-parts-gmbh.com\/fr\/extrudeuses-monovis\/","name":"Extrudeuses Monovis : CSW-PARTS GmbH, Fabrication, Entretien","isPartOf":{"@id":"https:\/\/www.csw-parts-gmbh.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.csw-parts-gmbh.com\/fr\/extrudeuses-monovis\/#primaryimage"},"image":{"@id":"https:\/\/www.csw-parts-gmbh.com\/fr\/extrudeuses-monovis\/#primaryimage"},"thumbnailUrl":"https:\/\/www.csw-parts-gmbh.com\/wp-content\/uploads\/2021\/02\/collage-einwelle.png","datePublished":"2020-12-21T09:53:17+00:00","dateModified":"2021-10-27T12:07:35+00:00","description":"Extrudeuses Monovis - R\u00e9paration, fabrication, maintenance, montage et d\u00e9montage et analyse. \u2605 CSW-PARTS GmbH - Extrudeuse - Technologie \u2605","breadcrumb":{"@id":"https:\/\/www.csw-parts-gmbh.com\/fr\/extrudeuses-monovis\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.csw-parts-gmbh.com\/fr\/extrudeuses-monovis\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.csw-parts-gmbh.com\/fr\/extrudeuses-monovis\/#primaryimage","url":"https:\/\/www.csw-parts-gmbh.com\/wp-content\/uploads\/2021\/02\/collage-einwelle.png","contentUrl":"https:\/\/www.csw-parts-gmbh.com\/wp-content\/uploads\/2021\/02\/collage-einwelle.png","width":960,"height":720,"caption":"Einwellenextruder - Extruder Experte"},{"@type":"BreadcrumbList","@id":"https:\/\/www.csw-parts-gmbh.com\/fr\/extrudeuses-monovis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.csw-parts-gmbh.com\/fr\/home\/"},{"@type":"ListItem","position":2,"name":"Extrudeuses Monovis"}]},{"@type":"WebSite","@id":"https:\/\/www.csw-parts-gmbh.com\/fr\/#website","url":"https:\/\/www.csw-parts-gmbh.com\/fr\/","name":"CSW-PARTS GmbH","description":"Spezialist f\u00fcr Extruder\u2013Technologie. Hauptverschlei\u00dfteile, wie Schnecken, Geh\u00e4usen, B\u00fcchsen, Wellen und Lochplatten, bis hin zu diversen anderen Verschlei\u00dfteilen.","publisher":{"@id":"https:\/\/www.csw-parts-gmbh.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.csw-parts-gmbh.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.csw-parts-gmbh.com\/fr\/#organization","name":"CSW-PARTS GmbH","url":"https:\/\/www.csw-parts-gmbh.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.csw-parts-gmbh.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.csw-parts-gmbh.com\/wp-content\/uploads\/2020\/12\/Logo-transparent-01-3.png","contentUrl":"https:\/\/www.csw-parts-gmbh.com\/wp-content\/uploads\/2020\/12\/Logo-transparent-01-3.png","width":803,"height":368,"caption":"CSW-PARTS GmbH"},"image":{"@id":"https:\/\/www.csw-parts-gmbh.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.csw-parts-gmbh.com\/fr\/wp-json\/wp\/v2\/pages\/4166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.csw-parts-gmbh.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.csw-parts-gmbh.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.csw-parts-gmbh.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.csw-parts-gmbh.com\/fr\/wp-json\/wp\/v2\/comments?post=4166"}],"version-history":[{"count":0,"href":"https:\/\/www.csw-parts-gmbh.com\/fr\/wp-json\/wp\/v2\/pages\/4166\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.csw-parts-gmbh.com\/fr\/wp-json\/wp\/v2\/media\/4099"}],"wp:attachment":[{"href":"https:\/\/www.csw-parts-gmbh.com\/fr\/wp-json\/wp\/v2\/media?parent=4166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}